{"id":1733,"date":"2016-09-30T10:14:06","date_gmt":"2016-09-30T08:14:06","guid":{"rendered":"http:\/\/giuseppeprincipiano.it\/?post_type=portfolio&#038;p=1733&#038;lang=en"},"modified":"2016-09-30T18:20:49","modified_gmt":"2016-09-30T16:20:49","slug":"harvest","status":"publish","type":"portfolio","link":"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/harvest\/","title":{"rendered":"Harvest"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_two_third-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-352b07ef7d3bc99b2e9f92e7a9e06bdb av_two_third  avia-builder-el-0  el_before_av_one_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_gallery-72bd66ad960dc94433480bad978c2e8d\">\n#top .avia-gallery.av-av_gallery-72bd66ad960dc94433480bad978c2e8d .avia-gallery-thumb a{\nwidth:14.2857%;\n}\n<\/style>\n<div  class='avia-gallery av-av_gallery-72bd66ad960dc94433480bad978c2e8d avia_animate_when_visible  avia-builder-el-1  avia-builder-el-no-sibling  avia_lazyload av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/harvest\/\"><div class='avia-gallery-big-wrapper'><a class='avia-gallery-big fakeLightbox lightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\"  data-onclick='1' title='Vendemmia-01' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1759 avia-img-lazy-loading-not-1759\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg\" title='Vendemmia-01' alt='' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-705x571.jpg 705w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><\/span><\/a><\/div><div class='avia-gallery-thumb'><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg' class='first_thumb lightbox ' data-onclick='1' title='Vendemmia-01'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1759 avia-img-lazy-loading-not-1759\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-01' alt='' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1759 avia-img-lazy-loading-1759\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg\" title='Vendemmia-01' alt='' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-01-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-1030x618.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-1030x618.jpg 1030w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-450x270.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-300x180.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-1500x900.jpg 1500w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-705x423.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-845x684.jpg' class='lightbox ' data-onclick='2' title='Vendemmia-02'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1760 avia-img-lazy-loading-not-1760\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-02' alt='Terreno asciutto in vigna' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1760 avia-img-lazy-loading-1760\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-845x684.jpg\" title='Vendemmia-02' alt='Terreno asciutto in vigna' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-845x684.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-02-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03.jpg' class='lightbox ' data-onclick='3' title='Vendemmia-03'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1761 avia-img-lazy-loading-not-1761\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-03' alt='Vendemmia tra i filari' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1761 avia-img-lazy-loading-1761\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03.jpg\" title='Vendemmia-03' alt='Vendemmia tra i filari' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-03-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04.jpg' class='lightbox ' data-onclick='4' title='Vendemmia-04'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1762 avia-img-lazy-loading-not-1762\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-04' alt='Uve mature' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1762 avia-img-lazy-loading-1762\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04.jpg\" title='Vendemmia-04' alt='Uve mature' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-04-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05.jpg' class='lightbox ' data-onclick='5' title='Vendemmia-05'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1763 avia-img-lazy-loading-not-1763\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-05' alt='La raccolta' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1763 avia-img-lazy-loading-1763\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05.jpg\" title='Vendemmia-05' alt='La raccolta' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-05-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06.jpg' class='lightbox ' data-onclick='6' title='Vendemmia-06'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1764 avia-img-lazy-loading-not-1764\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-06' alt='inizio vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1764 avia-img-lazy-loading-1764\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06.jpg\" title='Vendemmia-06' alt='inizio vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-06-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07.jpg' class='lightbox ' data-onclick='7' title='Vendemmia-07'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1765 avia-img-lazy-loading-not-1765\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-07' alt='verso fine vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1765 avia-img-lazy-loading-1765\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07.jpg\" title='Vendemmia-07' alt='verso fine vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-07-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08.jpg' class='first_thumb lightbox ' data-onclick='8' title='Vendemmia-08'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1766 avia-img-lazy-loading-not-1766\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-08' alt='Vendemmia in corso' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1766 avia-img-lazy-loading-1766\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08.jpg\" title='Vendemmia-08' alt='Vendemmia in corso' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-08-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09.jpg' class='lightbox ' data-onclick='9' title='Vendemmia-09'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1767 avia-img-lazy-loading-not-1767\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-09' alt='Vendemmia in corso' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1767 avia-img-lazy-loading-1767\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09.jpg\" title='Vendemmia-09' alt='Vendemmia in corso' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-09-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10.jpg' class='lightbox ' data-onclick='10' title='Vendemmia-10'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1768 avia-img-lazy-loading-not-1768\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-10' alt='Filari in vigna' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1768 avia-img-lazy-loading-1768\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10.jpg\" title='Vendemmia-10' alt='Filari in vigna' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-10-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11.jpg' class='lightbox ' data-onclick='11' title='Vendemmia-11'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1769 avia-img-lazy-loading-not-1769\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-11' alt='tralci di vite' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1769 avia-img-lazy-loading-1769\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11.jpg\" title='Vendemmia-11' alt='tralci di vite' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-11-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12.jpg' class='lightbox ' data-onclick='12' title='Vendemmia-12'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1770 avia-img-lazy-loading-not-1770\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-12' alt='Francesco Principiano vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1770 avia-img-lazy-loading-1770\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12.jpg\" title='Vendemmia-12' alt='Francesco Principiano vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-12-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13.jpg' class='lightbox ' data-onclick='13' title='Vendemmia-13'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1771 avia-img-lazy-loading-not-1771\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-13' alt='Francesco Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1771 avia-img-lazy-loading-1771\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13.jpg\" title='Vendemmia-13' alt='Francesco Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-13-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14.jpg' class='lightbox ' data-onclick='14' title='Vendemmia-14'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1772 avia-img-lazy-loading-not-1772\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-14' alt='Uva della vigna Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1772 avia-img-lazy-loading-1772\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14.jpg\" title='Vendemmia-14' alt='Uva della vigna Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-14-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15.jpg' class='first_thumb lightbox ' data-onclick='15' title='Vendemmia-15'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1773 avia-img-lazy-loading-not-1773\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-15' alt='vendemmia in vigna Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1773 avia-img-lazy-loading-1773\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15.jpg\" title='Vendemmia-15' alt='vendemmia in vigna Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-15-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16.jpg' class='lightbox ' data-onclick='16' title='Vendemmia-16'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1774 avia-img-lazy-loading-not-1774\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-16' alt='Francesco Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1774 avia-img-lazy-loading-1774\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16.jpg\" title='Vendemmia-16' alt='Francesco Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-16-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18.jpg' class='lightbox ' data-onclick='17' title='Vendemmia-18'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1776 avia-img-lazy-loading-not-1776\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-18' alt='Vendemmia dei vigneti Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1776 avia-img-lazy-loading-1776\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18.jpg\" title='Vendemmia-18' alt='Vendemmia dei vigneti Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-18-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20.jpg' class='lightbox ' data-onclick='18' title='Vendemmia-20'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1777 avia-img-lazy-loading-not-1777\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-20' alt='Periodo di vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1777 avia-img-lazy-loading-1777\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20.jpg\" title='Vendemmia-20' alt='Periodo di vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-20-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21.jpg' class='lightbox ' data-onclick='19' title='Vendemmia-21'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1778 avia-img-lazy-loading-not-1778\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-495x400.jpg\" width=\"495\" height=\"400\"  title='Vendemmia-21' alt='Inizio della vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1778 avia-img-lazy-loading-1778\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21.jpg\" title='Vendemmia-21' alt='Inizio della vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/Vendemmia-21-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30.jpg' class='lightbox ' data-onclick='20' title='vendemmia 30'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1779 avia-img-lazy-loading-not-1779\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-495x400.jpg\" width=\"495\" height=\"400\"  title='vendemmia 30' alt='Vendemmia nelle vigne Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1779 avia-img-lazy-loading-1779\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30.jpg\" title='vendemmia 30' alt='Vendemmia nelle vigne Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-30-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31.jpg' class='lightbox ' data-onclick='21' title='vendemmia 31'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1780 avia-img-lazy-loading-not-1780\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-495x400.jpg\" width=\"495\" height=\"400\"  title='vendemmia 31' alt='Francesco Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1780 avia-img-lazy-loading-1780\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31.jpg\" title='vendemmia 31' alt='Francesco Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-31-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32.jpg' class='first_thumb lightbox ' data-onclick='22' title='vendemmia 32'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1781 avia-img-lazy-loading-not-1781\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-495x400.jpg\" width=\"495\" height=\"400\"  title='vendemmia 32' alt='Francesco e Giuseppe Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1781 avia-img-lazy-loading-1781\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32.jpg\" title='vendemmia 32' alt='Francesco e Giuseppe Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-32-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33.jpg' class='lightbox ' data-onclick='23' title='vendemmia 33'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1782 avia-img-lazy-loading-not-1782\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-495x400.jpg\" width=\"495\" height=\"400\"  title='vendemmia 33' alt='Francesco e Giuseppe Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1782 avia-img-lazy-loading-1782\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33.jpg\" title='vendemmia 33' alt='Francesco e Giuseppe Principiano in vendemmia' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-33-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35.jpg' class='lightbox ' data-onclick='24' title='vendemmia 35'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1784 avia-img-lazy-loading-not-1784\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-495x400.jpg\" width=\"495\" height=\"400\"  title='vendemmia 35' alt='Vendemmia nei poderi principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1784 avia-img-lazy-loading-1784\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35.jpg\" title='vendemmia 35' alt='Vendemmia nei poderi principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-35-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34.jpg\" data-srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-705x571.jpg 705w\" data-sizes=\"(max-width: 845px) 100vw, 845px\" data-rel='gallery-1' data-prev-img='https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34.jpg' class='lightbox ' data-onclick='25' title='vendemmia 34'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1783 avia-img-lazy-loading-not-1783\"   src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-495x400.jpg\" width=\"495\" height=\"400\"  title='vendemmia 34' alt='Autunno nei poderi Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-705x571.jpg 705w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1783 avia-img-lazy-loading-1783\"  width=\"845\" height=\"684\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34.jpg\" title='vendemmia 34' alt='Autunno nei poderi Principiano' srcset=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34.jpg 845w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-450x364.jpg 450w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-300x243.jpg 300w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-768x622.jpg 768w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-495x400.jpg 495w, https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vendemmia-34-705x571.jpg 705w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-2a64de42b738552fe666ca889af77e28\">\n.flex_column.av-av_one_third-2a64de42b738552fe666ca889af77e28{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-2a64de42b738552fe666ca889af77e28 av_one_third  avia-builder-el-2  el_after_av_two_third  el_before_av_section  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Harvest<\/h3>\n<\/div><\/section><\/div><\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_1'  class='avia-section av-av_section-d18d8c2c81d10022ebd21ffa95322c35 main_color avia-section-default avia-no-shadow  avia-builder-el-4  el_after_av_one_third  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1733'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h4 style=\"text-align: center;\">Most Recent Entries<\/h4>\n<\/div><\/section>\n<div  class='hr av-av_hr-bad5bc90bcef2f12297bff634a297b07 hr-short  avia-builder-el-6  el_after_av_textblock  el_before_av_portfolio  avia-builder-el-last  hr-center'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  id=\"av-sc-portfolio-1\"  class=\"av-portfolio-grid-sorting-container\"><div class='sort_width_container  av-sort-yes' data-portfolio-id='1' ><div id='js_sort_items' ><div class='sort_by_cat hidden'><a href=\"#\" data-filter=\"all_sort\" class=\"all_sort_button active_sort\"><span class=\"inner_sort_button\"><span>All<\/span><small class=\"av-cat-count\"> 6 <\/small><\/span><\/a><\/div><\/div><\/div><div  class=' grid-sort-container isotope   no_margin-container with-excerpt-container grid-total-even grid-col-4 grid-links-' data-portfolio-id='1'><div data-ajax-id='1854' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-1854 grid-entry-overview grid-loop-1 grid-parity-odd   av_one_fourth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/cellar\/\" title='Cellar'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_la-cantina_04-260x185.jpg\" class=\"wp-image-1795 avia-img-lazy-loading-not-1795 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Cellar\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/cellar\/' title='Cellar'>Cellar<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='1734' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-1734 grid-entry-overview grid-loop-2 grid-parity-even   av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/grapes\/\" title='Grapes'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/grappoli-nebbiolo-04-260x185.jpg\" class=\"wp-image-1791 avia-img-lazy-loading-not-1791 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"Grappoli di nebbiolo\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Grapes\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/grapes\/' title='Grapes'>Grapes<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='1733' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-1733 grid-entry-overview grid-loop-3 grid-parity-odd   av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/harvest\/\" title='Harvest'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_le-vigne_nel-vignot_00-260x185.jpg\" class=\"wp-image-1785 avia-img-lazy-loading-not-1785 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Harvest\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/harvest\/' title='Harvest'>Harvest<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='1732' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-1732 grid-entry-overview grid-loop-4 grid-parity-even   av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/vineyards-in-winter\/\" title='Vineyards in winter'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vigneti_in_inverno_051-260x185.jpg\" class=\"wp-image-1740 avia-img-lazy-loading-not-1740 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vineyards in winter\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/vineyards-in-winter\/' title='Vineyards in winter'>Vineyards in winter<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='1706' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-1706 grid-entry-overview grid-loop-5 grid-parity-odd   av_one_fourth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/vineyards-in-spring\/\" title='Vineyards in spring'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_viti-in-primavera_13-260x185.jpg\" class=\"wp-image-1730 avia-img-lazy-loading-not-1730 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vineyards in spring\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/vineyards-in-spring\/' title='Vineyards in spring'>Vineyards in spring<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='1687' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-1687 grid-entry-overview grid-loop-6 grid-parity-even  post-entry-last   av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/vineyards-in-autumn\/\" title='Vineyards in autumn'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/vigneti-in-autunno_11-260x185.jpg\" class=\"wp-image-1698 avia-img-lazy-loading-not-1698 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vineyards in autumn\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/giuseppeprincipiano.it\/en\/portfolio-articoli\/vineyards-in-autumn\/' title='Vineyards in autumn'>Vineyards in autumn<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><\/div>   <!--   class=\"av-portfolio-grid-sorting-container\"  -->\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1733'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":1785,"template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[],"class_list":["post-1733","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Harvest - Giuseppe Principiano | Una eccellenza del Barolo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harvest - Giuseppe Principiano | Una eccellenza del Barolo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/\" \/>\n<meta property=\"og:site_name\" content=\"Giuseppe Principiano | Una eccellenza del Barolo\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-30T16:20:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_le-vigne_nel-vignot_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"845\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/\",\"url\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/\",\"name\":\"Harvest - Giuseppe Principiano | Una eccellenza del Barolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/principiano_le-vigne_nel-vignot_00.jpg\",\"datePublished\":\"2016-09-30T08:14:06+00:00\",\"dateModified\":\"2016-09-30T16:20:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/principiano_le-vigne_nel-vignot_00.jpg\",\"contentUrl\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/principiano_le-vigne_nel-vignot_00.jpg\",\"width\":845,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/portfolio-articoli\\\/vendemmia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harvest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/#website\",\"url\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/\",\"name\":\"Giuseppe Principiano | Una eccellenza del Barolo\",\"description\":\"Azienda Vinicola a Monforte d&#039;Alba, produttrice di Barolo e Barbera d&#039;Alba\",\"publisher\":{\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/#organization\",\"name\":\"Giuseppe e Francesco Principiano\",\"url\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/giuseppeprincipiano.it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo-principiano_450x156-300x104_NEW.png\",\"contentUrl\":\"http:\\\/\\\/giuseppeprincipiano.it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo-principiano_450x156-300x104_NEW.png\",\"width\":300,\"height\":104,\"caption\":\"Giuseppe e Francesco Principiano\"},\"image\":{\"@id\":\"https:\\\/\\\/giuseppeprincipiano.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harvest - Giuseppe Principiano | Una eccellenza del Barolo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/","og_locale":"en_US","og_type":"article","og_title":"Harvest - Giuseppe Principiano | Una eccellenza del Barolo","og_url":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/","og_site_name":"Giuseppe Principiano | Una eccellenza del Barolo","article_modified_time":"2016-09-30T16:20:49+00:00","og_image":[{"width":845,"height":684,"url":"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_le-vigne_nel-vignot_00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/","url":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/","name":"Harvest - Giuseppe Principiano | Una eccellenza del Barolo","isPartOf":{"@id":"https:\/\/giuseppeprincipiano.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/#primaryimage"},"image":{"@id":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/#primaryimage"},"thumbnailUrl":"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_le-vigne_nel-vignot_00.jpg","datePublished":"2016-09-30T08:14:06+00:00","dateModified":"2016-09-30T16:20:49+00:00","breadcrumb":{"@id":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/#primaryimage","url":"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_le-vigne_nel-vignot_00.jpg","contentUrl":"https:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/principiano_le-vigne_nel-vignot_00.jpg","width":845,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/giuseppeprincipiano.it\/portfolio-articoli\/vendemmia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giuseppeprincipiano.it\/en\/"},{"@type":"ListItem","position":2,"name":"Harvest"}]},{"@type":"WebSite","@id":"https:\/\/giuseppeprincipiano.it\/#website","url":"https:\/\/giuseppeprincipiano.it\/","name":"Giuseppe Principiano | Una eccellenza del Barolo","description":"Azienda Vinicola a Monforte d&#039;Alba, produttrice di Barolo e Barbera d&#039;Alba","publisher":{"@id":"https:\/\/giuseppeprincipiano.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giuseppeprincipiano.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/giuseppeprincipiano.it\/#organization","name":"Giuseppe e Francesco Principiano","url":"https:\/\/giuseppeprincipiano.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giuseppeprincipiano.it\/#\/schema\/logo\/image\/","url":"http:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/logo-principiano_450x156-300x104_NEW.png","contentUrl":"http:\/\/giuseppeprincipiano.it\/wp-content\/uploads\/2015\/07\/logo-principiano_450x156-300x104_NEW.png","width":300,"height":104,"caption":"Giuseppe e Francesco Principiano"},"image":{"@id":"https:\/\/giuseppeprincipiano.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/portfolio\/1733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/portfolio\/1733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/media\/1785"}],"wp:attachment":[{"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/media?parent=1733"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/tags?post=1733"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/giuseppeprincipiano.it\/en\/wp-json\/wp\/v2\/portfolio_entries?post=1733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}